{"id":1142,"date":"2023-09-22T17:29:08","date_gmt":"2023-09-22T20:29:08","guid":{"rendered":"https:\/\/interlabd.com\/es\/?p=1142"},"modified":"2023-09-22T17:37:50","modified_gmt":"2023-09-22T20:37:50","slug":"the-role-of-total-traceability-in-a-cssd-the-success-case-he-arturo-lopez-perez-foundation-of-chile-falp","status":"publish","type":"post","link":"https:\/\/interlabd.com\/pb\/caso-de-sucesso-falp\/","title":{"rendered":"O papel da rastreabilidade total na central de esteriliza\u00e7\u00e3o. O caso de sucesso da Funda\u00e7\u00e3o Arturo L\u00f3pez P\u00e9rez do Chile &#8211; FALP"},"content":{"rendered":"<p>Especializada em tratamentos oncol\u00f3gicos, a Funda\u00e7\u00e3o Arturo L\u00f3pez P\u00e9rez (FALP) <strong>foi o primeiro sanat\u00f3rio privado do Chile a ter rastreabilidade total at\u00e9 o paciente<\/strong>, desde a central de esteriliza\u00e7\u00e3o at\u00e9 os consult\u00f3rios de atendimento cl\u00ednico e a sala de cirurgia.<\/p>\n<p>Com mais de 50 anos de experi\u00eancia, a <a href=\"https:\/\/www.institutoncologicofalp.cl\/\" target=\"_blank\" rel=\"noopener\">FALP<\/a> \u00e9 uma organiza\u00e7\u00e3o sem fins lucrativos que busca proporcionar acesso oportuno a um tratamento integral em um centro oncol\u00f3gico altamente especializado. Seu modelo de sa\u00fade a torna um centro de refer\u00eancia na \u00e1rea, dedicado ao diagn\u00f3stico, tratamento, pesquisa e ensino. Al\u00e9m disso, contribui para o desenvolvimento da oncologia chilena com programas de educa\u00e7\u00e3o, preven\u00e7\u00e3o e detec\u00e7\u00e3o precoce do c\u00e2ncer.<\/p>\n<p>No entanto, a rastreabilidade total digitalizada e abrangente adotada pela FALP \u00e9 uma exce\u00e7\u00e3o: apesar de 88% dos respons\u00e1veis executivos e 86% dos m\u00e9dicos pesquisados na Am\u00e9rica Latina concordarem que a rastreabilidade e informa\u00e7\u00f5es em tempo real s\u00e3o essenciais para oferecer um melhor atendimento ao paciente, apenas 4 em cada 10 hospitais na regi\u00e3o investem o suficiente em efici\u00eancia m\u00e9dica, de acordo com o estudo <a href=\"https:\/\/www.zebra.com\/content\/dam\/zebra_new_ia\/en-us\/solutions-verticals\/vertical-solutions\/healthcare\/vision-study\/healthcare-vision-study-2022-es-la.pdf\" target=\"_blank\" rel=\"noopener\">&#8220;Hospitais mais Inteligentes e Conectados&#8221;<\/a> de 2022.<\/p>\n<p>A concretiza\u00e7\u00e3o do projeto de poder alcan\u00e7ar cada um dos pacientes e gerenciar de forma total e instant\u00e2nea o instrumental cir\u00fargico foi poss\u00edvel em 2018, quando a nova administra\u00e7\u00e3o aceitou a solicita\u00e7\u00e3o da chefe da central de esteriliza\u00e7\u00e3o, Gerthy R\u00edos, uma enfermeira de profiss\u00e3o, que observava o tempo perdido na localiza\u00e7\u00e3o de equipamentos e suprimentos m\u00e9dicos. Somente entre 2011 e 2017, foram realizadas na institui\u00e7\u00e3o 642.577 consultas m\u00e9dicas, atendendo a 86.364 novos pacientes e realizando 36.451 cirurgias, por isso uma ferramenta de monitoramento, rastreabilidade e gest\u00e3o permitiria garantir um atendimento m\u00e9dico seguro e livre de infec\u00e7\u00f5es.<\/p>\n<p>Um dos principais problemas era <strong>transmitir \u00e0 administra\u00e7\u00e3o a import\u00e2ncia da rastreabilidade e monitoramento do instrumental cir\u00fargico para a seguran\u00e7a do paciente<\/strong>, assim como os custos crescentes que n\u00e3o estavam sendo contabilizados. Dessa forma, as perdas desnecess\u00e1rias, as falhas t\u00e9cnicas e a grande quantidade de reprocesos eram frequentes, em grande parte devido \u00e0 falta de registro do parque de instrumental cir\u00fargico e dispositivos m\u00e9dicos dispon\u00edveis. Esses custos estavam absorvendo todo o or\u00e7amento da central de esteriliza\u00e7\u00e3o, que apenas resolvia os problemas do dia a dia, mas n\u00e3o encontrava tempo para dinamizar seu trabalho atrav\u00e9s de um padr\u00e3o de processos que permitisse otimizar a qualidade do servi\u00e7o.<\/p>\n<p>A central de esteriliza\u00e7\u00e3o precisava tra\u00e7ar um plano de a\u00e7\u00e3o a m\u00e9dio prazo, com indicadores e metas precisas de produtividade, custos e gest\u00e3o de recursos humanos, al\u00e9m da quantidade de falhas no processo de esteriliza\u00e7\u00e3o.<\/p>\n<p>O primeiro passo desse plano de a\u00e7\u00e3o foi <a href=\"https:\/\/interlabd.com\/pb\/como-escolher-o-software-ideal-para-uma-central-de-esterilizacao\/\" target=\"_blank\" rel=\"noopener\">escolher um software de rastreabilidade e gest\u00e3o<\/a> que permitisse n\u00e3o apenas a contagem do instrumental, funcionalidade muito comum na maioria dos sistemas desse tipo, mas que tamb\u00e9m fosse escal\u00e1vel para outros setores cr\u00edticos, como a sala de Endoscopia, Salas de Cirurgia e diversos setores de atendimento cl\u00ednico. Dessa forma, seria otimizado o uso, rota\u00e7\u00e3o e gest\u00e3o do instrumental cir\u00fargico e dispositivos m\u00e9dicos em toda a institui\u00e7\u00e3o, atrav\u00e9s da rastreabilidade total at\u00e9 o paciente. Essas fun\u00e7\u00f5es requeridas eram altamente espec\u00edficas e cr\u00edticas, ent\u00e3o a escolha do fornecedor representava um desafio: o sistema estaria presente em todas as tarefas do dia a dia, por isso o suporte e a indu\u00e7\u00e3o do pessoal da central deveriam estar de acordo com as necessidades recorrentes de um hospital oncol\u00f3gico dessa envergadura, tornando o fornecedor tamb\u00e9m um parceiro estrat\u00e9gico da central de esteriliza\u00e7\u00e3o.<\/p>\n<p>Ap\u00f3s mais de 3 anos de experi\u00eancia com o sistema Interlab, a FALP hoje \u00e9 refer\u00eancia no Chile em termos de <strong>rastreabilidade total<\/strong>, que chegou a todas as \u00e1reas com uma grande ades\u00e3o institucional. Os benef\u00edcios foram vis\u00edveis em diferentes n\u00edveis. Em primeiro lugar, a perda de instrumental foi reduzida e sua rota\u00e7\u00e3o foi otimizada gra\u00e7as aos registros digitais e \u00e0 rastreabilidade do instrumental de reutiliza\u00e7\u00e3o para reutiliza\u00e7\u00e3o. Al\u00e9m disso, o desempenho da equipe foi aprimorado e a sobrecarga de trabalho de cada turno de trabalho foi reduzida. Por fim, o plano de a\u00e7\u00e3o justificou, em parte, a expans\u00e3o da nova central de esteriliza\u00e7\u00e3o, com equipamentos de \u00faltima gera\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>Especializada em tratamentos oncol\u00f3gicos, a Funda\u00e7\u00e3o Arturo L\u00f3pez P\u00e9rez (FALP) foi o primeiro sanat\u00f3rio privado do Chile a ter rastreabilidade<\/p>\n","protected":false},"author":2,"featured_media":1144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/posts\/1142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/comments?post=1142"}],"version-history":[{"count":1,"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/posts\/1142\/revisions"}],"predecessor-version":[{"id":1150,"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/posts\/1142\/revisions\/1150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/media\/1144"}],"wp:attachment":[{"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/media?parent=1142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/categories?post=1142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interlabd.com\/pb\/wp-json\/wp\/v2\/tags?post=1142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}