{"id":3782,"date":"2024-05-23T15:32:26","date_gmt":"2024-05-23T18:32:26","guid":{"rendered":"https:\/\/interlabd.com\/es\/?p=3782"},"modified":"2024-07-10T15:05:06","modified_gmt":"2024-07-10T18:05:06","slug":"interlab-tuvo-un-paso-exitoso-en-el-ii-congreso-iberoamericano-de-esterilizacion","status":"publish","type":"post","link":"https:\/\/interlabd.com\/es\/interlab-tuvo-un-paso-exitoso-en-el-ii-congreso-iberoamericano-de-esterilizacion\/","title":{"rendered":"Interlab tuvo un paso exitoso en el II Congreso Iberoamericano de Esterilizaci\u00f3n"},"content":{"rendered":"<p>Interlab, empresa l\u00edder en el desarrollo de soluciones para la trazabilidad y gesti\u00f3n de instrumental quir\u00fargico y dispositivos m\u00e9dicos, tuvo un exitoso paso por el II Congreso Iberoamericano de Esterilizaci\u00f3n, celebrado del 16 al 18 de mayo en el Centro de Convenciones Las Am\u00e9ricas de Cartagena, Colombia. Esto se debe a que tanto la presentaci\u00f3n de su innovadora herramienta tecnol\u00f3gica como el taller que dict\u00f3 su director, Ezequiel Giuliani, contaron con una importante convocatoria. De esta manera, la empresa sigue aportando con orgullo desde su lugar a la comunidad m\u00e9dica y de salud.<\/p>\n<p>Interlab present\u00f3 su avanzada tecnolog\u00eda dise\u00f1ada para optimizar los procesos de esterilizaci\u00f3n y gesti\u00f3n de instrumental quir\u00fargico, que contribuye a mejorar la eficiencia y seguridad en entornos hospitalarios. En ese marco, una gran cantidad de interesados se acercaron al stand 19 para conocer en profundidad el impacto significativo que tiene la propuesta de Interlab.<\/p>\n<p>Hubo un inter\u00e9s espec\u00edfico sobre el el taller \u00abSoftware de trazabilidad y gesti\u00f3n total hasta el paciente\u00bb que dict\u00f3 Giuliani. Durante su exposici\u00f3n proporcion\u00f3 una visi\u00f3n detallada de c\u00f3mo la tecnolog\u00eda de Interlab puede integrarse en los sistemas de atenci\u00f3n m\u00e9dica para garantizar la trazabilidad y la gesti\u00f3n integral del instrumental quir\u00fargico.<\/p>\n<p>El taller cont\u00f3 con una alta convocatoria y una participaci\u00f3n activa por parte de los asistentes, lo que subraya el inter\u00e9s y la relevancia de las soluciones propuestas por Interlab en el \u00e1mbito de la esterilizaci\u00f3n y gesti\u00f3n de instrumental m\u00e9dico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3785\" src=\"https:\/\/interlabd.com\/wp-content\/uploads\/2024\/05\/tallerr-1-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/interlabd.com\/wp-content\/uploads\/2024\/05\/tallerr-1-300x218.jpg 300w, https:\/\/interlabd.com\/wp-content\/uploads\/2024\/05\/tallerr-1-1024x745.jpg 1024w, https:\/\/interlabd.com\/wp-content\/uploads\/2024\/05\/tallerr-1-768x559.jpg 768w, https:\/\/interlabd.com\/wp-content\/uploads\/2024\/05\/tallerr-1-1536x1118.jpg 1536w, https:\/\/interlabd.com\/wp-content\/uploads\/2024\/05\/tallerr-1-2048x1491.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La reciente presentaci\u00f3n de Interlab en el II Congreso Iberoamericano de Esterilizaci\u00f3n reafirma su posici\u00f3n como l\u00edder en el sector y su compromiso continuo con la innovaci\u00f3n y el avance en el campo de la salud y la esterilizaci\u00f3n m\u00e9dica.<\/p>\n<p>Los interesados en conocer m\u00e1s sobre las soluciones de Interlab pueden ingresar al sitio www.interlabd.com.<\/p>","protected":false},"excerpt":{"rendered":"<p>Interlab, empresa l\u00edder en el desarrollo de soluciones para la trazabilidad y gesti\u00f3n de instrumental quir\u00fargico y dispositivos m\u00e9dicos, tuvo<\/p>\n","protected":false},"author":3,"featured_media":3783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/posts\/3782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/comments?post=3782"}],"version-history":[{"count":2,"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/posts\/3782\/revisions"}],"predecessor-version":[{"id":3787,"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/posts\/3782\/revisions\/3787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/media\/3783"}],"wp:attachment":[{"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/media?parent=3782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/categories?post=3782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interlabd.com\/es\/wp-json\/wp\/v2\/tags?post=3782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}